{"id":20616,"date":"2022-12-06T04:27:00","date_gmt":"2022-12-06T04:27:00","guid":{"rendered":"https:\/\/ifesworld.org\/?post_type=prayerline&#038;p=20616"},"modified":"2022-12-06T16:28:06","modified_gmt":"2022-12-06T16:28:06","slug":"comprendiendo-urbana","status":"publish","type":"prayerline","link":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/","title":{"rendered":"Comprendiendo Urbana"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">La conferencia misionera <a href=\"https:\/\/urbana.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Urbana<\/a>, organizada por el <a href=\"https:\/\/intervarsity.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Movimiento Estudiantil de IFES InterVarsity USA<\/a>, tiene un legado impresionante. Desde el a\u00f1o 1946, Urbana ha llamado a miles de estudiantes de los Estados Unidos a responder al llamado de Dios sobre sus vidas, inspirando a otros movimientos estudiantiles en el mundo con una visi\u00f3n parecida para las misiones. Muchas personas de todo el mundo echan la vista atr\u00e1s y se\u00f1alan c\u00f3mo su experiencia en Urbana fue un punto de inflexi\u00f3n en el que entregaron sus vidas a Jes\u00fas de una forma nueva.\u00a0<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-embed wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Urbana 22 Student Missions Conference Promo - It&#039;s Time | InterVarsity Christian Fellowship\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/DOLXGP71634?feature=oembed&#038;cc_load_policy=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">La conferencia Urbana se celebrar\u00e1 a finales de este mes. No obstante, Urbana 2022 tiene lugar en un panorama cultural bien diferente al que le precedi\u00f3. Los a\u00f1os que han pasado desde la \u00faltima conferencia celebrada en 2018 han sido tumultuosos y divisorios tanto pol\u00edticamente, como social y econ\u00f3micamente para Estados Unidos y, tristemente, la iglesia tampoco se ha escapado de esta divisi\u00f3n. En este Prayerline, una de las organizadoras de la conferencia, Anna Lee-Winans, comparte c\u00f3mo podemos orar por la pr\u00f3xima conferencia.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Anna es consciente de algunos contextos complicados. Por ejemplo, el hecho de que \u201cmuchas misiones cristianas tienen el peso del colonialismo\u201d. Pero Anna quiere que los estudiantes vean que tanto Dios como la iglesia global les invita a ser testigos del Evangelio de Jes\u00fas \u201chasta los confines de la tierra\u201d (Hechos 1:8). En esta conferencia de Urbana, hay una invitaci\u00f3n para que los l\u00edderes cristianos nativos americanos vengan y muestren a los delegados c\u00f3mo \u201caproximarse de una forma adecuada\u201d. Con estas personas, <a href=\"https:\/\/native.intervarsity.org\/?_gl=1*1b3mt2m*_ga*ODQ0NjkwNzM3LjE2MzEyODA0MDc.*_ga_SYLND0PGPH*MTY3MDM0MzM1My4yNS4xLjE2NzAzNDMzNjAuNTMuMC4w\">el ministerio de InterVarsity dedicado a los Nativos Americanos, Native InterVarsity<\/a>, han desarrollado relaciones a lo largo de los a\u00f1os. Es importante, nos dice Anna, porque \u201cdiscernir la invitaci\u00f3n de Dios de una forma correcta y conectar con humildad con una nueva cultura es una forma de honrar profundamente la imagen de Dios\u201d.\u00a0<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Urbana atrae a los estudiantes \u201ca un lugar clave para la iglesia Estadounidense para acceder a la voz de la iglesia global y la iglesia en los m\u00e1rgenes. Mediante la exposici\u00f3n del libro de los Hechos de los Ap\u00f3stoles, los servicios multiculturales, testimonios y las oportunidades de liderazgo y coaching, nuestra esperanza es que Urbana se convierta en una experiencia de discipulado\u201d. En una iglesia fracturada por las divisiones pol\u00edticas y culturales, podemos orar para que los estudiantes en un momento cultural polarizado puedan encontrar el camino hacia delante en Cristo, que se llenen las lagunas de sus ideolog\u00edas con la plenitud del Evangelio. \u201cPara los estudiantes, tanto de trasfondos conservadores como liberales, incluyen esos que est\u00e1n deconstruyendo su fe y aquellos que han sincretizado su fe con la cultura Estadounidense, Urbana es un sitio para ser discipulado de una forma poderosa. Queremos que los estudiantes sean \u2018verdaderamente libres\u2019 (Juan 8:36) para conectar con este momento cultural, confiando en Jes\u00fas para esta estaci\u00f3n y siguiendo la invitaci\u00f3n del Esp\u00edritu Santo.\u201d&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Por favor, ora con nosotros por Urbana \u201822 e InterVarsity USA:&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Ora para que al menos 10.000 estudiantes de InterVarsity vengan a la conferencia con corazones abiertos para que su fe se vea \u201creconstruida\u201d por la verdad del Evangelio.&nbsp;<\/li><li>Ora para que Urbana sea el lugar donde las divisiones sean sanadas; donde los que han luchado con los problemas culturales puedan ver un aperitivo del Jes\u00fas real que ayuda a que todo vuelva a su sitio.&nbsp;<\/li><li>Ora para que Dios obre mediante Urbana y por medio de los estudiantes de InterVarsity para traer las buenas nuevas de su poder real, eterno y dador de vida mediante Jes\u00fas, tanto en los Estados Unidos como en la iglesia global.&nbsp;<\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Gracias por apoyar en oraci\u00f3n a InterVarsity USA. Si sientes que quieres apoyar al movimiento de forma econ\u00f3mica, puedes hacerlo <a href=\"https:\/\/give.ifesworld.org\/customgiving?t=3&amp;d=NAUSA_TRANS&amp;s=UKPL&amp;a=0\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a>.&nbsp;&nbsp;<\/p>\n<\/div>","protected":false},"featured_media":20612,"template":"","area":[710,907],"theme":[],"class_list":["post-20616","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-america-del-norte","area-estados-unidos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprendiendo Urbana &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"La conferencia misionera Urbana, organizada por el Movimiento Estudiantil de IFES InterVarsity USA, tiene un legado impresionante. Desde el a\u00f1o 1946,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprendiendo Urbana &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"La conferencia misionera Urbana, organizada por el Movimiento Estudiantil de IFES InterVarsity USA, tiene un legado impresionante. Desde el a\u00f1o 1946,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-06T16:28:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/12\/2013.01.01_stuart-jones_0860.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/\",\"name\":\"Comprendiendo Urbana &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2013.01.01_stuart-jones_0860.jpg\",\"datePublished\":\"2022-12-06T04:27:00+00:00\",\"dateModified\":\"2022-12-06T16:28:06+00:00\",\"description\":\"La conferencia misionera Urbana, organizada por el Movimiento Estudiantil de IFES InterVarsity USA, tiene un legado impresionante. Desde el a\u00f1o 1946,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2013.01.01_stuart-jones_0860.jpg\",\"contentUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2013.01.01_stuart-jones_0860.jpg\",\"width\":700,\"height\":465},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/comprendiendo-urbana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comprendiendo Urbana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprendiendo Urbana &#183; IFES Prayerline","description":"La conferencia misionera Urbana, organizada por el Movimiento Estudiantil de IFES InterVarsity USA, tiene un legado impresionante. Desde el a\u00f1o 1946,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/","og_locale":"es_ES","og_type":"article","og_title":"Comprendiendo Urbana &#183; IFES Prayerline","og_description":"La conferencia misionera Urbana, organizada por el Movimiento Estudiantil de IFES InterVarsity USA, tiene un legado impresionante. Desde el a\u00f1o 1946,","og_url":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/","og_site_name":"IFES","article_modified_time":"2022-12-06T16:28:06+00:00","og_image":[{"width":700,"height":465,"url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/12\/2013.01.01_stuart-jones_0860.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/","url":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/","name":"Comprendiendo Urbana &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/ifesworld.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/#primaryimage"},"image":{"@id":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/#primaryimage"},"thumbnailUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/12\/2013.01.01_stuart-jones_0860.jpg","datePublished":"2022-12-06T04:27:00+00:00","dateModified":"2022-12-06T16:28:06+00:00","description":"La conferencia misionera Urbana, organizada por el Movimiento Estudiantil de IFES InterVarsity USA, tiene un legado impresionante. Desde el a\u00f1o 1946,","breadcrumb":{"@id":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/#primaryimage","url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/12\/2013.01.01_stuart-jones_0860.jpg","contentUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/12\/2013.01.01_stuart-jones_0860.jpg","width":700,"height":465},{"@type":"BreadcrumbList","@id":"https:\/\/ifesworld.org\/es\/prayerline\/comprendiendo-urbana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Comprendiendo Urbana"}]},{"@type":"WebSite","@id":"https:\/\/ifesworld.org\/es\/#website","url":"https:\/\/ifesworld.org\/es\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/ifesworld.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifesworld.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ifesworld.org\/es\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/ifesworld.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifesworld.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/ifesworld.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline\/20616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/media\/20612"}],"wp:attachment":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=20616"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=20616"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=20616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}