{"id":18454,"date":"2022-03-29T11:02:57","date_gmt":"2022-03-29T10:02:57","guid":{"rendered":"https:\/\/ifesworld.org\/?post_type=prayerline&#038;p=18454"},"modified":"2022-03-29T11:02:59","modified_gmt":"2022-03-29T10:02:59","slug":"proclamacion-del-evangelio-en-la-copa-africana-de-naciones","status":"publish","type":"prayerline","link":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/","title":{"rendered":"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52 partidos de la competici\u00f3n, los estudiantes estaban <a href=\"http:\/\/gbeec.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">GBEEC, el movimiento nacional de Camer\u00fan,<\/a> proclamando el evangelio.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Guy y Magloire son miembros de GBEEC. Aprovecharon la competici\u00f3n para que GBEEC colaborase con m\u00e1s de 20 organizaciones cristianas, en una iniciativa dirigida por la organizaci\u00f3n de Guy, <a href=\"https:\/\/www.facebook.com\/missionnairessansfrontieres\/\" target=\"_blank\" rel=\"noreferrer noopener\">Missionaires Sans Fronti\u00e8res,<\/a> para compartir el evangelio en cada uno de los partidos. Guy envi\u00f3 equipos de evangelizaci\u00f3n a cada estadio aprovechando que hab\u00eda gente congregada. En la hora previa al partido, los estudiantes se colocaron en las esquinas de las calles y en lugares estrat\u00e9gicos con m\u00fasica cristiana, predicando el mensaje del evangelio y acerc\u00e1ndose a las personas de forma individual para hablarles del Se\u00f1or. Magloire, cuya organizaci\u00f3n se llama Op\u00e9ration Jeunesse Pr\u00e9cieuse, tambi\u00e9n estuvo presente y cuenta que m\u00e1s de 3,000 aficionados escucharon el mensaje del evangelio.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">No fue f\u00e1cil. \u201cLas personas en general se mostraron muy hostiles,\u201d confes\u00f3 Magloire. \u201cLa gente nos insultaba y se re\u00eda de nosotros, pero, por la gracia de Dios, algunos escucharon y algunos pensaron sobre lo que est\u00e1bamos compartiendo\u201d.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Lo mejor es que, seg\u00fan Magloire, unas 500 personas hicieron una confesi\u00f3n de fe en Jes\u00fas por primera vez. A medida que proclamaban el evangelio con fe, \u201cmuchos estudiantes se sintieron animado a seguir predicando el evangelio y otros decidieron seguir a Jes\u00fas\u201d, al ver el trabajo y la valent\u00eda de sus compa\u00f1eros.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Ora con Magloire por el trabajo de seguimiento que se est\u00e1 haciendo despu\u00e9s de la evangelizaci\u00f3n, y por los estudiantes de GBEEC:&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-list\">\n<ul class=\"wp-block-list\"><li>Da gracias a Dios por el coraje y el buen trabajo de todos los que hicieron posible que se proclamara el evangelio de esta forma.\u00a0<\/li><li>Ora para que muchas m\u00e1s de las 3,000 personas que escucharon el evangelio acepten a Jes\u00fas como su Salvador y Se\u00f1or personal.\u00a0<\/li><li>Ora por aquellos que hicieron una confesi\u00f3n de fe: que el equipo sepa cuidarlos y empiece a discipularlos.\u00a0<\/li><li>Ora para que el Se\u00f1or provea fondos para que puedan seguir repartiendo folletos.\u00a0\u00a0<\/li><li>Ora para que los estudiantes sigan estando motivados para compartir el evangelio y que sigan amando a\u00fan m\u00e1s a Jes\u00fas y siendo sal y luz en la universidad.\u00a0<\/li><\/ul>\n<\/div>","protected":false},"featured_media":18452,"template":"","area":[707,845],"theme":[],"class_list":["post-18454","prayerline","type-prayerline","status-publish","has-post-thumbnail","hentry","area-africa-francofona","area-camerun"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0 &#183; IFES Prayerline<\/title>\n<meta name=\"description\" content=\"A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0 &#183; IFES Prayerline\" \/>\n<meta property=\"og:description\" content=\"A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-29T10:02:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/03\/Cameroon-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/\",\"name\":\"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0 &#183; IFES Prayerline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cameroon-scaled.jpg\",\"datePublished\":\"2022-03-29T10:02:57+00:00\",\"dateModified\":\"2022-03-29T10:02:59+00:00\",\"description\":\"A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cameroon-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cameroon-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/prayerline\\\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prayerline\",\"item\":\"https:\\\/\\\/ifesworld.org\\\/en\\\/prayerline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0 &#183; IFES Prayerline","description":"A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/","og_locale":"es_ES","og_type":"article","og_title":"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0 &#183; IFES Prayerline","og_description":"A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52","og_url":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/","og_site_name":"IFES","article_modified_time":"2022-03-29T10:02:59+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/03\/Cameroon-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/","url":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/","name":"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0 &#183; IFES Prayerline","isPartOf":{"@id":"https:\/\/ifesworld.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/#primaryimage"},"image":{"@id":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/#primaryimage"},"thumbnailUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/03\/Cameroon-scaled.jpg","datePublished":"2022-03-29T10:02:57+00:00","dateModified":"2022-03-29T10:02:59+00:00","description":"A principios de febrero de este a\u00f1o, el equipo de f\u00fatbol de Senegal gan\u00f3 la Copa Africana de Naciones. Y en medio de todo el furor y la emoci\u00f3n de los 52","breadcrumb":{"@id":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/#primaryimage","url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/03\/Cameroon-scaled.jpg","contentUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/03\/Cameroon-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/ifesworld.org\/es\/prayerline\/proclamacion-del-evangelio-en-la-copa-africana-de-naciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Prayerline","item":"https:\/\/ifesworld.org\/en\/prayerline\/"},{"@type":"ListItem","position":3,"name":"Proclamaci\u00f3n del evangelio en la Copa Africana de Naciones\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/ifesworld.org\/es\/#website","url":"https:\/\/ifesworld.org\/es\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/ifesworld.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifesworld.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ifesworld.org\/es\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/ifesworld.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifesworld.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/ifesworld.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline\/18454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/prayerline"}],"about":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/types\/prayerline"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/media\/18452"}],"wp:attachment":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=18454"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=18454"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=18454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}