{"id":19302,"date":"2022-07-28T04:13:00","date_gmt":"2022-07-28T03:13:00","guid":{"rendered":"https:\/\/ifesworld.org\/?post_type=conexion&#038;p=19302"},"modified":"2022-08-16T11:13:16","modified_gmt":"2022-08-16T10:13:16","slug":"en-el-medio-de-la-oscuridad","status":"publish","type":"conexion","link":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/","title":{"rendered":"En el medio de la oscuridad"},"content":{"rendered":"<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><em><em>La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera mano acerca de c\u00f3mo, a pesar de estar en el medio de la oscuridad de la guerra, Dios est\u00e1 obrando. Aqu\u00ed leer\u00e1s las perspectivas de los estudiantes, obreros y graduados de IFES de Ucrania y de Rusia.<\/em><\/em><\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><em>La segunda parte de esta publicaci\u00f3n est\u00e1 <a href=\"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad-2a-parte\/\">disponible aqu\u00ed<\/a><\/em>, e<em> incluye historias de c\u00f3mo la comunidad ha respondido ampliamente al impacto de la guerra.<\/em><\/p>\n<\/div>\n\n<div class=\"wp-block block-core-heading\">\n<h2 class=\"wp-block-heading\">Anna: \u201cNo temo morir.\u201d\u00a0<\/h2>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Anna era una estudiante <a href=\"https:\/\/www.instagram.com\/ccx_npu\/\" target=\"_blank\" rel=\"noreferrer noopener\">en Kiev<\/a> antes de la guerra. Ella es originalmente de Lysychansk, en la zona del Domb\u00e1s. Durante meses, su ciudad estaba en el frente y la guerra era tan feroz que el presidente ucraniano Volodymyr Zelensky la pronunci\u00f3 una <a href=\"https:\/\/www.bbc.co.uk\/news\/world-europe-61711028\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cciudad muerta<\/a>.\u201d No obstante, aunque todo el mundo huy\u00f3 de Lysychansk, Anna regres\u00f3 para trabajar con un <a href=\"https:\/\/www.instagram.com\/go.dobro.ua\/\" target=\"_blank\" rel=\"noreferrer noopener\">equipo peque\u00f1o en su iglesia,<\/a> ayudando a quienes se quedaron atr\u00e1s.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Aunque Anna inicialmente se quedara en Lysychansk, proporcionando cuidados b\u00e1sicos para quienes lo necesitasen, a primeros de abril, la lucha se acerc\u00f3 tanto que destruy\u00f3 los edificios alrededor de su iglesia. El equipo cambi\u00f3 de perspectiva. Se posicionaron un poco m\u00e1s lejos y estuvieron entrando y saliendo de Lysychansk y evacuaron a m\u00e1s de 600 personas de la ciudad.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Una evacuada, una se\u00f1ora mayor, intent\u00f3 suicidarse varias veces antes de que el equipo de Anna llegase hasta ella. Tras hacer que revisasen a la mujer en el hospital, encontraron un sitio en el que pudiera alojarse y compartieron el Evangelio con ella.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">El equipo est\u00e1 trabajando en varios sitios peligrosos. Un d\u00eda, en el viaje hasta Lysychansk, se encontraron con un periodista internacional viajando en un veh\u00edculo armado en esa misma direcci\u00f3n. En su viaje de vuelta unas pocas horas m\u00e1s tarde, descubrieron que <a href=\"https:\/\/www.bfmtv.com\/international\/bfmtv-a-l-immense-douleur-d-annoncer-la-disparition-de-frederic-leclerc-imhoff-journaliste-reporter-d-images-tue-en-ukraine_AV-202205300454.html\" target=\"_blank\" rel=\"noreferrer noopener\">hab\u00eda muerto<\/a> por una bomba. En otra ocasi\u00f3n, el equipo tuvo que cubrirse de un bombardeo bajo un puente. Sin embargo, cuando par\u00f3, se volvieron a subir a su furgoneta y continuaron su viaje hasta Lysychansk.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">[Embed Instagram post <a href=\"https:\/\/www.instagram.com\/p\/CeW3UEkKCqV\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com\/p\/CeW3UEkKCqV\/<\/a> ]&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Dado que Lysychansk est\u00e1 bajo ocupaci\u00f3n Rusa en estos momentos, el equipo ya no puede acceder a la ciudad. Igualmente, han proporcionado ayuda humanitaria en otros sitios mientras trabajan entre los peligros y se tienen que refugiar de un bombardeo cuando fuera necesario. \u201cDios siempre ha provisto para ellos\u201d, dijo Marina, obrera de CCX que empez\u00f3 a ser mentora de Anna tras la guerra. \u201cEstaba muy preocupada por ella.\u201c \u201dPero cuando compart\u00ed mis preocupaciones, Anna me dijo: \u2018No tengo miedo a nada.\u201c \u201dS\u00e9 que si muero estar\u00e9 con Jes\u00fas.\u201c \u201dDios me ha llamado para hacer esto y esta es la misi\u00f3n que debo cumplir\u2019.\u201d&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-heading\">\n<h2 class=\"wp-block-heading\"><strong>Marina: \u201cDios est\u00e1 trabajando\u201d<\/strong>&nbsp;<\/h2>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Eran las 5 de la madrugada, cuando Marina se despert\u00f3 con las explosiones resonando por Kiev. Su tel\u00e9fono estaba lleno de mensajes de amigos preocupados y las carreteras de la ciudad ya estaban bloqueadas por cientos de coches. Se sent\u00f3 en tensi\u00f3n con su familia a la hora del desayuno, la pregunta de su hermanastra de 12 a\u00f1os trajo la situaci\u00f3n a un primer plano: \u201c\u00bfVoy a morirme?\u201d&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201cS\u00cd.\u201d La respuesta de Marina fue contundente. Entonces explic\u00f3 que \u201cno sabemos si ser\u00e1 ahora o dentro de muchos a\u00f1os, lo que importa es si eres salva.\u201d En ese momento, entre oraciones y l\u00e1grimas, la hermana de Marina acept\u00f3 a Jes\u00fas. Echando la vista atr\u00e1s, Marina ahora puede reconocer las semillas que Dios ha plantado. \u201cEn el mes anterior\u201d, nos explica, \u201c[mi hermana] ha estado preguntando mucho acerca de la Biblia y de la vida tras la muerte. Dios realmente estaba obrando en su vida.\u201d La hermana de Marina ha estado asistiendo al programa <a href=\"https:\/\/discipleship.explo.red\/\" target=\"_blank\" rel=\"noreferrer noopener\">Discipleship Explored<\/a> y ha ayudado con el trabajo humanitario en su iglesia.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Desde que comenz\u00f3 la guerra, Marina ha continuado con su trabajo con <a href=\"https:\/\/ccx.org.ua\/\" target=\"_blank\" rel=\"noreferrer noopener\">CCX, el movimiento estudiantil de Ucrania<\/a>. Se re\u00fane en remoto con grupos de Kiev, Cherkasy y Mykolaiv \u2013 otra ciudad en primera l\u00ednea. Los estudiantes en todos estos grupos se han extendido por toda Europa. Adem\u00e1s de trabajar para mantener a las comunidades estudiantes fuertes antes de la guerra, Marina est\u00e1 ayudando a comenzar un nuevo grupo en una universidad en Kiev, estableciendo amistades con cerca de 20 estudiantes. Es m\u00e1s, como parte de una iniciativa unida con <a href=\"https:\/\/chsa.org.pl\/\" target=\"_blank\" rel=\"noreferrer noopener\">ChSA, el movimiento nacional de Polonia,<\/a> CCX Ucrania proporciona cajas de regalos durante la Pascua y materiales de evangelizaci\u00f3n a la universidad y a los estudiantes de escuela secundaria en Kiev.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Lejos de casa, Marina sab\u00eda que muchos Ucranianos estaban perdiendo la oportunidad de reunirse y adorar en su propio idioma. Obligada a abandonar Kiev en febrero, Marina pas\u00f3 dos meses en el oeste de Ucrania, antes de irse a Bucarest. Se hizo un nuevo, aunque temporal, hogar en el apartamento de Heidi, una obrera de IFES Europa, una casa donde hab\u00eda un piano. Esto significaba que Marina pod\u00eda celebrar <a href=\"https:\/\/www.instagram.com\/p\/Cdgc_izqPHL\/\" target=\"_blank\" rel=\"noreferrer noopener\">noches de adoraci\u00f3n en vivo en Instagram<\/a>. Desde entonces ha hablado a un p\u00fablico de 13.000 j\u00f3venes, en la conferencia <a href=\"https:\/\/www.christival.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Christival<\/a>, en Alemania, acerca de su experiencia con la obra de Dios durante la guerra.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Marina espera volver a Kiev a finales de julio para ayudar a los obreros y estudiantes de CCX a prepararse para el nuevo a\u00f1o acad\u00e9mico. Aunque no sabe si habr\u00e1 otro ataque, la iglesia en su ciudad est\u00e1 llena de gente, hay cerca de 100 personas nuevas cada domingo. No hay suficientes cristianos para ayudarles a todos y la iglesia se ha quedado sin Biblias. Seg\u00fan nos relata Marina, casi todos son personas mayores de Mariupol, Kharkiv e Izum, donde han perdido sus hogares y trabajos. No tienen nada. Pero encuentran esperanza cuando vienen a la iglesia.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Los estudiantes han acabado sus ex\u00e1menes y ahora necesitan tener claridad acerca de si deben continuar sus estudios en las universidades de Ucrania, o si es mejor inscribirse en universidades Europeas, nos explica Marina. Por favor, ora para que se renueven las fuerzas de los obreros de CCX, muchos de los cuales han comenzado sus vidas de nuevo en otras ciudades. Ora para que Dios provea para sus necesidades y les d\u00e9 fuerzas para servir a otros.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-heading\">\n<h2 class=\"wp-block-heading\">Dmitri*: \u201cHay algo m\u00e1s universal que la pol\u00edtica.\u201d\u00a0<\/h2>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u201c\u2019\u00bfC\u00f3mo lo sobrellevas, Dmitri?\u2019&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u2018Con oraci\u00f3n.\u2019&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u2018\u00bfFunciona?\u2019 Mi colega era incr\u00e9dulo.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">\u2018S\u00ed,\u2019 respond\u00ed.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Y entonces tuvimos que dejar de hablar.\u201d&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">La ciudad en la que vive Dmitri est\u00e1 al norte del c\u00edrculo polar \u00e1rtico y es muy remota. Ah\u00ed Dmitri particip\u00f3 en el movimiento estudiantil ruso en la universidad, e hizo de ese sitio su hogar. Sin embargo, Dmitri ha estado intentando ayudar a gente de Ucrania desde el estallido de la guerra. Utiliz\u00f3 sus conexiones para encontrar alojamiento para una familia de Mariupol y les ayud\u00f3 a huir a Noruega. Dos veces en semana, Dmitri tambi\u00e9n traduce como parte del proyecto <a href=\"https:\/\/psalmsforukraine.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Salmos para Ucrania<\/a>, trabajo que le entrega a Kenny, un obrero de <a href=\"https:\/\/www.uccf.org.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\">UCCF, el movimiento nacional del Reino Unido<\/a>. Este proyecto sirve a los ucranianos cuyo primer idioma es el<a href=\"https:\/\/psalmsforukraine.com\/ru-home\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Ruso<\/a>.&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Dmitri reconoce que es muy complicado hablar sobre la guerra en Rusia. \u201cNo tengo muchos amigos con los que pueda hablar de estas cosas. Las personas dicen que es complicado y que no disponemos de mucha informaci\u00f3n para evitar hacer un juicio. Mucha gente est\u00e1 escondiendo su cabeza en la arena.\u201d&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Desgraciadamente, este mal aplica a los cristianos tambi\u00e9n. \u201cAunque las iglesias locales hablaban acerca de la justicia y la igualdad primero, no est\u00e1n dispuestos a hablar de forma p\u00fablica,\u201d nos relata Dmitri. \u201cSer protestante en Rusia ya era peligroso, y lo es m\u00e1s ahora mismo. Al mismo tiempo, tengo amigos cristianos en Crimea que ven la guerra de una forma completamente distinta. Es muy dif\u00edcil.\u201d&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\">As\u00ed se establece una nueva realidad, Dmitri nos pide que oremos contra la \u201cfatiga b\u00e9lica.\u201d \u201cNecesitamos energ\u00eda espiritual para seguir orando. En un momento sientes que te has quedado sin palabras. Ora tambi\u00e9n por la sanidad de ambas naciones. No importa c\u00f3mo termine la guerra, eventualmente tendr\u00e1n que mirarse unos a otros a los ojos. Especialmente, orad para que los creyentes sigan activos, que sigan siendo sal y luz, compartiendo esperanza, aunque sientan que no la hay.\u201d&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><em>La semana que viene publicaremos m\u00e1s perspectivas de estos pa\u00edses circundantes, a la par que ampliamos la informaci\u00f3n sobre el papel que IFES ha desarrollado para apoyar a los estudiantes y obreros afectados.&nbsp;<\/em>&nbsp;<\/p>\n<\/div>\n\n<div class=\"wp-block block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><em>*Hemos cambiado los nombres por motivos de seguridad.<\/em>&nbsp;<\/p>\n<\/div>","protected":false},"featured_media":19299,"template":"","area":[705],"theme":[],"class_list":["post-19302","conexion","type-conexion","status-publish","has-post-thumbnail","hentry","area-eurasia-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En el medio de la oscuridad &#183; IFES Conexi\u00f3n Blog<\/title>\n<meta name=\"description\" content=\"La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En el medio de la oscuridad &#183; IFES Conexi\u00f3n Blog\" \/>\n<meta property=\"og:description\" content=\"La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/\" \/>\n<meta property=\"og:site_name\" content=\"IFES\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T10:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/07\/War-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/\",\"name\":\"En el medio de la oscuridad &#183; IFES Conexi\u00f3n Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/War-2.jpg\",\"datePublished\":\"2022-07-28T03:13:00+00:00\",\"dateModified\":\"2022-08-16T10:13:16+00:00\",\"description\":\"La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/War-2.jpg\",\"contentUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/War-2.jpg\",\"width\":1280,\"height\":808},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/en-el-medio-de-la-oscuridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexi\u00f3n\",\"item\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"En el medio de la oscuridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\",\"name\":\"IFES\",\"description\":\"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#organization\",\"name\":\"IFES \u00b7 International Fellowship of Evangelical Students\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"contentUrl\":\"https:\\\/\\\/ifesworld.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ifeslogo.png\",\"width\":262,\"height\":262,\"caption\":\"IFES \u00b7 International Fellowship of Evangelical Students\"},\"image\":{\"@id\":\"https:\\\/\\\/ifesworld.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En el medio de la oscuridad &#183; IFES Conexi\u00f3n Blog","description":"La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/","og_locale":"es_ES","og_type":"article","og_title":"En el medio de la oscuridad &#183; IFES Conexi\u00f3n Blog","og_description":"La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera","og_url":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/","og_site_name":"IFES","article_modified_time":"2022-08-16T10:13:16+00:00","og_image":[{"width":1280,"height":808,"url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/07\/War-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/","url":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/","name":"En el medio de la oscuridad &#183; IFES Conexi\u00f3n Blog","isPartOf":{"@id":"https:\/\/ifesworld.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/#primaryimage"},"image":{"@id":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/#primaryimage"},"thumbnailUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/07\/War-2.jpg","datePublished":"2022-07-28T03:13:00+00:00","dateModified":"2022-08-16T10:13:16+00:00","description":"La guerra en Ucrania ha impactado a la obra de IFES en muchos niveles. En esta edici\u00f3n de Conexi\u00f3n de dos partes, compartiremos las historias de primera","breadcrumb":{"@id":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/#primaryimage","url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/07\/War-2.jpg","contentUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2022\/07\/War-2.jpg","width":1280,"height":808},{"@type":"BreadcrumbList","@id":"https:\/\/ifesworld.org\/es\/blog\/en-el-medio-de-la-oscuridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ifesworld.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conexi\u00f3n","item":"https:\/\/ifesworld.org\/es\/blog\/"},{"@type":"ListItem","position":3,"name":"En el medio de la oscuridad"}]},{"@type":"WebSite","@id":"https:\/\/ifesworld.org\/es\/#website","url":"https:\/\/ifesworld.org\/es\/","name":"IFES","description":"A movement of students sharing and living out the good news of Jesus Christ. Locally. Nationally. Globally.","publisher":{"@id":"https:\/\/ifesworld.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifesworld.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ifesworld.org\/es\/#organization","name":"IFES \u00b7 International Fellowship of Evangelical Students","url":"https:\/\/ifesworld.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifesworld.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","contentUrl":"https:\/\/ifesworld.org\/wp-content\/uploads\/2019\/06\/ifeslogo.png","width":262,"height":262,"caption":"IFES \u00b7 International Fellowship of Evangelical Students"},"image":{"@id":"https:\/\/ifesworld.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/conexion\/19302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/conexion"}],"about":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/types\/conexion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/media\/19299"}],"wp:attachment":[{"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/media?parent=19302"}],"wp:term":[{"taxonomy":"area","embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/area?post=19302"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/ifesworld.org\/es\/wp-json\/wp\/v2\/theme?post=19302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}